{"id":97,"date":"2024-06-06T12:52:51","date_gmt":"2024-06-06T12:52:51","guid":{"rendered":"https:\/\/goldendreamsevents.com\/?page_id=97"},"modified":"2026-05-10T20:58:23","modified_gmt":"2026-05-10T20:58:23","slug":"home","status":"publish","type":"page","link":"https:\/\/goldendreamsevents.com\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"97\" class=\"elementor elementor-97\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"has_eae_slider elementor-element elementor-element-f806ef9 e-flex e-con-boxed e-con e-parent\" data-id=\"f806ef9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-bbee3c3 e-con-full e-flex e-con e-parent\" data-id=\"bbee3c3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0bbc816 elementor-widget elementor-widget-heading\" data-id=\"0bbc816\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Upcoming Event <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c73635c elementor-widget elementor-widget-image-carousel\" data-id=\"c73635c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:1,&quot;speed&quot;:6000,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/12\/PHOTO-2025-12-09-17-31-15-807x1024.jpg\" alt=\"PHOTO-2025-12-09-17-31-15\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/12\/SnapInsta.to_582801236_18180204388357825_5942881850814445182_n-819x1024.webp\" alt=\"SnapInsta.to_582801236_18180204388357825_5942881850814445182_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2026\/05\/Copy-of-MOHANLAL-LIVE-IN-GERMANY-01-819x1024.png\" alt=\"Copy of MOHANLAL LIVE IN GERMANY 01\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-03-19-at-14.48.03-819x1024.jpeg\" alt=\"WhatsApp Image 2026-03-19 at 14.48.03\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2026\/05\/MOHANLAL-12-819x1024.png\" alt=\"MOHANLAL (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2026\/05\/ALL-togther-1-819x1024.png\" alt=\"ALL togther (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/12\/SnapInsta.to_587289169_18249007093291171_6161865696744609458_n-798x1024.jpg\" alt=\"SnapInsta.to_587289169_18249007093291171_6161865696744609458_n\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-948e113 elementor-widget elementor-widget-spacer\" data-id=\"948e113\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4285cc1 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4285cc1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"3\"><span data-path-to-node=\"3,1\"><span class=\"citation-103\">Golden Dreams, in partnership with Business Kerala and UK Event Life, proudly presents the <\/span><b><span class=\"citation-103\">UK-India Business &amp; Cultural Summit 2026<\/span><\/b><\/span><span data-path-to-node=\"3,3\">. <\/span><span data-path-to-node=\"3,5\"><span class=\"citation-102\">Join us this June in London for a landmark event featuring <\/span><b><span class=\"citation-102\">Kerala Mart<\/span><\/b><span class=\"citation-102\">, a premier business exhibition, and <\/span><b><span class=\"citation-102\">Mohanlal Live<\/span><\/b><span class=\"citation-102\">, a mega-cultural show at the OVO Arena Wembley<\/span><\/span><span data-path-to-node=\"3,7\">. <\/span><span data-path-to-node=\"3,9\"><span class=\"citation-101\">Experience the ultimate fusion of entrepreneurial excellence and cinematic history<\/span><\/span><span data-path-to-node=\"3,11\">.<\/span><\/p><div class=\"source-inline-chip-container ng-star-inserted\">\u00a0<\/div><div class=\"source-inline-chip-container ng-star-inserted\">\u00a0<\/div><div class=\"source-inline-chip-container ng-star-inserted\">\u00a0<\/div><div class=\"source-inline-chip-container ng-star-inserted\">\u00a0<\/div><div class=\"source-inline-chip-container ng-star-inserted\">\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-914cdbb elementor-widget elementor-widget-heading\" data-id=\"914cdbb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Previous Events<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da434a6 elementor-widget elementor-widget-image-carousel\" data-id=\"da434a6\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:1,&quot;speed&quot;:6000,&quot;slides_to_show&quot;:&quot;2&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.30-1-783x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.30 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.30-2-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.30 (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.27-1-783x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.27 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/keli-ponnonam-2025--819x1024.jpg\" alt=\"keli ponnonam 2025 -\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.30-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.30\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.26-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.26\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 7\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.27-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.27\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-6cea51f e-con-full e-flex e-con e-parent\" data-id=\"6cea51f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf1b5b9 elementor-widget elementor-widget-heading\" data-id=\"bf1b5b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Golden Dream Events<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eae0e67 elementor-widget elementor-widget-heading\" data-id=\"eae0e67\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bringing the World Together Through Art, Culture &amp; Showbiz\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40c1c02 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"40c1c02\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"445\" data-end=\"837\">At <strong data-start=\"448\" data-end=\"471\">Golden Dream Events<\/strong>, we transform cultural dreams into reality. With over two decades of global experience, we specialize in organizing <strong data-start=\"588\" data-end=\"615\">spectacular stage shows<\/strong>, <strong data-start=\"617\" data-end=\"639\">cultural festivals<\/strong>, <strong data-start=\"641\" data-end=\"667\">film location scouting<\/strong>, and <strong data-start=\"673\" data-end=\"708\">traditional Indian performances<\/strong>. Our footprint spans across <strong data-start=\"737\" data-end=\"774\">Europe, the U.S.A., and Australia<\/strong>, and we continue to spread the joy of entertainment worldwide.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b928fa elementor-widget elementor-widget-heading\" data-id=\"7b928fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">25+ Years of Excellence<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eebd67a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"eebd67a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"1590\" data-end=\"1696\">Pioneers in cultural entertainment since 2000, with events hosted in <strong data-start=\"1659\" data-end=\"1695\">London, Rome, Vienna, and Zurich.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-925e2e0 elementor-widget elementor-widget-spacer\" data-id=\"925e2e0\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-13bf581 e-flex e-con-boxed e-con e-parent\" data-id=\"13bf581\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-86e555e e-con-full e-flex e-con e-child\" data-id=\"86e555e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c11e2f5 elementor-widget elementor-widget-image\" data-id=\"c11e2f5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/16.jpg\" class=\"attachment-large size-large wp-image-1651\" alt=\"\" srcset=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/16.jpg 720w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/16-300x200.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abb016d elementor-widget elementor-widget-heading\" data-id=\"abb016d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Live Shows &amp; Concerts\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40dae5f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"40dae5f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>From star-studded performances to intimate cultural evenings, our shows are crafted to mesmerize diverse audiences<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-598de33 e-con-full e-flex e-con e-child\" data-id=\"598de33\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-472ecc3 elementor-widget elementor-widget-image\" data-id=\"472ecc3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/13-1.jpg\" class=\"attachment-large size-large wp-image-1648\" alt=\"\" srcset=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/13-1.jpg 720w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/13-1-300x200.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27a72d3 elementor-widget elementor-widget-heading\" data-id=\"27a72d3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Film &amp; Location Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aeebab elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2aeebab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"1206\" data-end=\"1336\">Scouting the perfect location or connecting with artistic talents? We bridge the gap between filmmakers and culture-rich settings.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-0763657 e-con-full e-flex e-con e-child\" data-id=\"0763657\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82ac7fd elementor-widget elementor-widget-image\" data-id=\"82ac7fd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/12-2.jpg\" class=\"attachment-large size-large wp-image-1647\" alt=\"\" srcset=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/12-2.jpg 720w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/12-2-300x200.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f66b5d8 elementor-widget elementor-widget-heading\" data-id=\"f66b5d8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Artist Management<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54a15cd elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"54a15cd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"1371\" data-end=\"1522\">We work with some of the finest talents from the Malayalam film industry, mimicry artists, musicians, and dancers\u2014bringing only the best to your stage.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-12cd211 e-con-full e-flex e-con e-child\" data-id=\"12cd211\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51cb946 elementor-widget elementor-widget-image\" data-id=\"51cb946\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"446\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-10-at-01.34.36_26c24cd5-e1746821330303-1024x446.jpg\" class=\"attachment-large size-large wp-image-2091\" alt=\"\" srcset=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-10-at-01.34.36_26c24cd5-e1746821330303-1024x446.jpg 1024w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/WhatsApp-Image-2025-05-10-at-01.34.36_26c24cd5-e1746821330303-768x334.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7e2189 elementor-widget elementor-widget-heading\" data-id=\"e7e2189\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cultural Exchange Festivals<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bab144 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5bab144\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"1058\" data-end=\"1167\">We curate unforgettable experiences celebrating the richness of Indian tradition alongside global influences.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-c669aca e-flex e-con-boxed e-con e-parent\" data-id=\"c669aca\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-311e9ce e-con-full e-flex e-con e-child\" data-id=\"311e9ce\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c83d105 elementor-widget elementor-widget-heading\" data-id=\"c83d105\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Upcoming Events<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53db748 elementor-widget elementor-widget-image-carousel\" data-id=\"53db748\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:1,&quot;speed&quot;:6000,&quot;slides_to_show&quot;:&quot;2&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/12\/SnapInsta.to_582801236_18180204388357825_5942881850814445182_n-819x1024.webp\" alt=\"SnapInsta.to_582801236_18180204388357825_5942881850814445182_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/12\/SnapInsta.to_587289169_18249007093291171_6161865696744609458_n-798x1024.jpg\" alt=\"SnapInsta.to_587289169_18249007093291171_6161865696744609458_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/12\/PHOTO-2025-12-09-17-31-15-807x1024.jpg\" alt=\"PHOTO-2025-12-09-17-31-15\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2685d09 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2685d09\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/goldendreamsevents.com\/index.php\/current-events\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-8d50a41 e-con-full e-flex e-con e-child\" data-id=\"8d50a41\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b74d6d4 elementor-widget elementor-widget-heading\" data-id=\"b74d6d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Past Events<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67f0957 elementor-widget elementor-widget-image-carousel\" data-id=\"67f0957\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay_speed&quot;:1,&quot;speed&quot;:6000,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/02\/5a7f47cc-b97c-4ec7-a16e-de071914ddee-724x1024.webp\" alt=\"5a7f47cc-b97c-4ec7-a16e-de071914ddee\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-01-at-22.12.05_b95ea462-724x1024.webp\" alt=\"WhatsApp Image 2025-02-01 at 22.12.05_b95ea462\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/02\/WhatsApp-Image-2025-02-01-at-22.12.04_ab51814d-724x1024.webp\" alt=\"WhatsApp Image 2025-02-01 at 22.12.04_ab51814d\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/57886d15-9cfd-477e-8eba-7ab16860b784-819x1024.jpeg\" alt=\"57886d15-9cfd-477e-8eba-7ab16860b784\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/eb846d7f-9555-41bf-8358-342cd187777a-819x1024.jpeg\" alt=\"eb846d7f-9555-41bf-8358-342cd187777a\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-11.43.02-AM-e1746817971777.jpeg\" alt=\"WhatsApp Image 2024-07-03 at 11.43.02 AM\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/6289c16b-670f-4a5b-bdec-42ca00f20f3b-737x1024.jpeg\" alt=\"6289c16b-670f-4a5b-bdec-42ca00f20f3b\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/7acd6a86-07ac-4a7b-b1c6-f936d9871215-737x1024.jpeg\" alt=\"7acd6a86-07ac-4a7b-b1c6-f936d9871215\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/318c5930-4f93-4b2a-ad23-06cdcf204f42-723x1024.jpeg\" alt=\"318c5930-4f93-4b2a-ad23-06cdcf204f42\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/89ef4079-bac1-472f-b331-04a81808edb0.jpeg\" alt=\"89ef4079-bac1-472f-b331-04a81808edb0\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/Black-White-Mega-Show.jpg\" alt=\"Black-White-Mega-Show\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/summer-in-europe.jpg\" alt=\"summer-in-europe\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/comedy-stars-in-australia.jpg\" alt=\"comedy-stars-in-australia\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/notice-1.jpg\" alt=\"notice\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/mohanlals-show.jpg\" alt=\"mohanlal&#039;s-show\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/jayaram-show.jpg\" alt=\"jayaram-show\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/Manikilukkam-1.jpg\" alt=\"Manikilukkam (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/dreams2023.jpg\" alt=\"dreams2023\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/event-not.jpg\" alt=\"event-not\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/Current-Events1-Copy-e1746817940117.jpg\" alt=\"Current-Events1 - Copy\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/06\/P8-673x1024.png\" alt=\"P8\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/da8a8c4a-40e5-4bd0-a5c2-9e92c3f48a85-e1746817958384.jpeg\" alt=\"da8a8c4a-40e5-4bd0-a5c2-9e92c3f48a85\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/9c5f4776-b5dc-4bb2-a339-2134647c233b-697x1024.jpeg\" alt=\"9c5f4776-b5dc-4bb2-a339-2134647c233b\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/ba765b6d-fa4e-4b90-a7c9-c9b0d72026d0-697x1024.jpeg\" alt=\"ba765b6d-fa4e-4b90-a7c9-c9b0d72026d0\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2024\/07\/0ecaf8fc-9d84-4b4a-a47b-fc8317125ec9.jpeg\" alt=\"0ecaf8fc-9d84-4b4a-a47b-fc8317125ec9\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-17.24.21-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 17.24.21\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-17.24.21-7-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 17.24.21 (7)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-17.24.21-6-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 17.24.21 (6)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"29 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-17.24.21-5-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 17.24.21 (5)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"30 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-17.24.21-3-701x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 17.24.21 (3)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"31 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-17.24.21-4-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 17.24.21 (4)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"32 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-17.24.21-2-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 17.24.21 (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"33 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.27-2-783x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.27 (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"34 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.27-1-783x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.27 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"35 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.30-2-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.30 (2)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"36 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.27-819x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.27\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"37 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-26-at-16.50.30-1-783x1024.jpeg\" alt=\"WhatsApp Image 2025-07-26 at 16.50.30 (1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"38 of 38\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/keli-ponnonam-2025-819x1024.jpg\" alt=\"keli ponnonam 2025\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af815b2 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"af815b2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/goldendreamsevents.com\/index.php\/past-events-3\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">View More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-01fdae9 e-flex e-con-boxed e-con e-parent\" data-id=\"01fdae9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66faa8f elementor-widget elementor-widget-heading\" data-id=\"66faa8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Meet the Visionaries Behind the Magic\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-eefe2c1 e-grid e-con-full e-con e-child\" data-id=\"eefe2c1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10e7fdc elementor-widget elementor-widget-image\" data-id=\"10e7fdc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/sinjo-golden-dreams-events-819x1024.png\" class=\"attachment-large size-large wp-image-2115\" alt=\"\" srcset=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/sinjo-golden-dreams-events-819x1024.png 819w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/sinjo-golden-dreams-events-240x300.png 240w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/sinjo-golden-dreams-events-768x960.png 768w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/sinjo-golden-dreams-events.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddabf58 elementor-widget elementor-widget-image\" data-id=\"ddabf58\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/geo-golden-dreams-events-1-1-819x1024.png\" class=\"attachment-large size-large wp-image-2117\" alt=\"\" srcset=\"https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/geo-golden-dreams-events-1-1-819x1024.png 819w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/geo-golden-dreams-events-1-1-240x300.png 240w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/geo-golden-dreams-events-1-1-768x960.png 768w, https:\/\/goldendreamsevents.com\/wp-content\/uploads\/2025\/05\/geo-golden-dreams-events-1-1.png 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d75345a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d75345a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"\" data-start=\"2224\" data-end=\"2424\"><strong data-start=\"2224\" data-end=\"2257\"> Sinjo Nellissery &amp;\u00a0 Geo Mathew<\/strong>\u00a0lead the team with creativity, passion, and an unshakable belief in the power of performance. Every event is more than just a show\u2014it&#8217;s a shared memory in the making.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-4fcb308 e-flex e-con-boxed e-con e-parent\" data-id=\"4fcb308\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29a71f3 elementor-widget elementor-widget-heading\" data-id=\"29a71f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why Choose Golden Dream Events?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-6aba537 e-flex e-con-boxed e-con e-parent\" data-id=\"6aba537\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-5cd7296 e-con-full e-flex e-con e-child\" data-id=\"5cd7296\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4f12d0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"f4f12d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u2705 Proven track record in cultural events\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e355eb5 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e355eb5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u2705 Global reach with local expertise\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6d2566 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c6d2566\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u2705 Engaging storytelling through art\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"has_eae_slider elementor-element elementor-element-7a8404c e-con-full e-flex e-con e-child\" data-id=\"7a8404c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d87f8d2 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"d87f8d2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u2705 Innovative, customized event concepts\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc1c73d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"cc1c73d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u2705 25 year Experience in events management <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e086101 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e086101\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u2705 Strong artist &amp; sponsor collaboration\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Upcoming Event Golden Dreams, in partnership with Business Kerala and UK Event Life, proudly presents the UK-India Business &amp; Cultural Summit 2026. Join us this June in London for a landmark event featuring Kerala Mart, a premier business exhibition, and Mohanlal Live, a mega-cultural show at the OVO Arena Wembley. Experience the ultimate fusion of&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-97","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/goldendreamsevents.com\/index.php\/wp-json\/wp\/v2\/pages\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goldendreamsevents.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/goldendreamsevents.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/goldendreamsevents.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/goldendreamsevents.com\/index.php\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":559,"href":"https:\/\/goldendreamsevents.com\/index.php\/wp-json\/wp\/v2\/pages\/97\/revisions"}],"predecessor-version":[{"id":2221,"href":"https:\/\/goldendreamsevents.com\/index.php\/wp-json\/wp\/v2\/pages\/97\/revisions\/2221"}],"wp:attachment":[{"href":"https:\/\/goldendreamsevents.com\/index.php\/wp-json\/wp\/v2\/media?parent=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}